{"id":9757,"date":"2026-01-30T12:24:37","date_gmt":"2026-01-30T11:24:37","guid":{"rendered":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/?p=9757"},"modified":"2026-02-02T10:08:24","modified_gmt":"2026-02-02T09:08:24","slug":"las-10-caracteristicas-principales-de-solidworks-xdesign-en-2025","status":"publish","type":"post","link":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/solidworks-blog\/3dexperience\/las-10-caracteristicas-principales-de-solidworks-xdesign-en-2025\/","title":{"rendered":"Las 10 caracter\u00edsticas principales de SOLIDWORKS xDesign en 2025"},"content":{"rendered":"<p>Ahora que 2025 est\u00e1 llegando a su fin, me gustar\u00eda compartir algunas de las principales mejoras que se han incorporado este a\u00f1o a su soluci\u00f3n basada en navegador favorita: SOLIDWORKS xDesign. Para empezar, es a\u00fan m\u00e1s f\u00e1cil acceder a todas las funciones de xApps en una soluci\u00f3n, ya que xDesign est\u00e1 ahora disponible como un \u00fanico producto que incluye funciones de dise\u00f1o param\u00e9trico de piezas y ensamblajes, modelado de subdivisi\u00f3n, chapa met\u00e1lica, dise\u00f1o de marcos, herramientas de moldes, dibujos, MBD y renderizado.<\/p>\n<p>Aqu\u00ed encontrar\u00e1 las 10 principales mejoras, entre las que he incluido mis favoritas: el nuevo dise\u00f1o de la p\u00e1gina de inicio, las vistas detalladas para documentaci\u00f3n t\u00e9cnica y la tecnolog\u00eda de visualizaci\u00f3n de realidad extendida (ER).<\/p>\n<ol>\n<li><strong>Comience proyectos y acceda al contenido de aprendizaje desde la nueva p\u00e1gina de inicio<\/strong><\/li>\n<\/ol>\n<p>La p\u00e1gina de inicio de xDesign se ha redise\u00f1ado y cuenta con muchos recursos para ayudarle a avanzar r\u00e1pido, mejorar su productividad y servirle de fuente de inspiraci\u00f3n, entre los que se incluyen:<\/p>\n<ul>\n<li>Acceso inmediato a proyectos recientes, v\u00eddeos \u00fatiles y proyectos de ejemplo.<\/li>\n<li>Acceso m\u00e1s r\u00e1pido al Centro de aprendizaje directamente desde el panel lateral de la plataforma para que pueda mejorar sus habilidades y encontrar respuestas r\u00e1pidamente.<\/li>\n<li>La nueva p\u00e1gina \u00abPara usted\u00bb incluye art\u00edculos interesantes, publicaciones de 3DSwym y v\u00eddeos en l\u00ednea.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/newlandingpagenov2625.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9758 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/newlandingpagenov2625.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/newlandingpagenov2625.png 800w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/newlandingpagenov2625-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/newlandingpagenov2625-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/newlandingpagenov2625-728x410.png 728w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\">2. <strong>Cree dibujos listos para producci\u00f3n con las nuevas funciones de dise\u00f1o<\/strong><\/p>\n<p>Cree dibujos detallados que transmitan claramente los requisitos de fabricaci\u00f3n, incluidas las operaciones internas, los requisitos de ensamblaje y las ubicaciones de taladros gracias a las siguientes mejoras:<\/p>\n<ul>\n<li>Cree f\u00e1cilmente vistas de secci\u00f3n y detalle desde el entorno de dibujo, usando los procesos de trabajo habituales con l\u00edneas de secci\u00f3n y c\u00edrculos de recorte.<\/li>\n<li>Visualice con mayor claridad la orientaci\u00f3n y las relaciones entre piezas gracias a la funci\u00f3n de vistas detalladas en su documentaci\u00f3n t\u00e9cnica. Cree la vista detallada en 3D y a\u00f1\u00e1dala f\u00e1cilmente a la hoja de dibujo.<\/li>\n<li>Complete la definici\u00f3n del producto para componentes con formas redondeadas gracias a la posibilidad de agregar centros de c\u00edrculo y acotar los bordes de silueta<\/li>\n<\/ul>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sectionviewnov2625.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9759 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sectionviewnov2625.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sectionviewnov2625.png 800w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sectionviewnov2625-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sectionviewnov2625-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sectionviewnov2625-728x410.png 728w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\">3.<strong> Optimice las revisiones de dise\u00f1o con funciones de realidad extendida: realidad aumentada y realidad virtual <\/strong><\/p>\n<p>Mejore las revisiones de dise\u00f1o y la comprensi\u00f3n del espacio gracias a la posibilidad de visualizar sus modelos en un entorno de realidad extendida (XR) envolvente.<\/p>\n<p>Inicie experiencias de realidad virtual o aumentada directamente desde xDesign para ver sus modelos e interactuar con ellos a escala en entornos virtuales o reales usando un caso, una tablet o un tel\u00e9fono m\u00f3vil.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/xrnov262520_1_.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9760 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/xrnov262520_1_.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/xrnov262520_1_.png 800w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/xrnov262520_1_-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/xrnov262520_1_-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/xrnov262520_1_-728x410.png 728w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\">4.<strong> Colabore f\u00e1cilmente con enlaces para compartir<\/strong><\/p>\n<p>Colabore f\u00e1cilmente y comparta enlaces directos a productos f\u00edsicos, para agilizar la retroalimentaci\u00f3n y la colaboraci\u00f3n en sus proyectos de dise\u00f1o.<\/p>\n<p>Comparta cualquier producto f\u00edsico de xDesign con sus compa\u00f1eros mediante un enlace. Al hacer clic en \u00e9l, el producto se abrir\u00e1 directamente en su sesi\u00f3n de xDesign, facilitando la colaboraci\u00f3n y la revisi\u00f3n.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sharablelinknov2625.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9761 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sharablelinknov2625.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sharablelinknov2625.png 800w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sharablelinknov2625-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sharablelinknov2625-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/sharablelinknov2625-728x410.png 728w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\">5. <strong>Cree modelos m\u00e1s detallados con nuevas operaciones de modelado<\/strong><\/p>\n<p>Cree modelos m\u00e1s detallados y precisos con herramientas de modelado sofisticadas, adem\u00e1s de herramientas de comentarios inteligentes que le ayudar\u00e1n a construir m\u00e1s r\u00e1pido, detectar problemas y solucionarlos gracias a la orientaci\u00f3n de expertos. Estas son algunas de las mejoras del modelado:<\/p>\n<ul>\n<li>El nuevo comando Ajustar proyecta perfiles de croquis sobre superficies objetivo y generar estampados, grabados o inscripciones.<\/li>\n<li>El nuevo comando An\u00e1lisis de croquis proporciona herramientas para corregir croquis demasiado definidos, resolver problemas de referencias que faltan o se han quedado colgadas, y cerrar perfiles de croquis abiertos.<\/li>\n<li>Los comandos Equidistancia y Vaciado ahora ofrecen indicadores visuales en el modelo para identificar las \u00e1reas de fallo de las operaciones.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/wrapcommandnov2625.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9762 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/wrapcommandnov2625.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/wrapcommandnov2625.png 800w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/wrapcommandnov2625-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/wrapcommandnov2625-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/wrapcommandnov2625-728x410.png 728w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\">6.<strong> Agilice los flujos de trabajo de documentaci\u00f3n con vistas de dibujo generativas<\/strong><\/p>\n<p>Utilice el poder de la inteligencia artificial (IA) para acabar con las tareas repetitivas y agilizar el proceso de creaci\u00f3n de dibujos. Para activar la creaci\u00f3n y colocaci\u00f3n autom\u00e1tica de vistas, marque la casilla \u00abGenerar vistas de dibujo\u00bb en el comando Nueva hoja.<\/p>\n<p>Una vez activada, el comando crear\u00e1 autom\u00e1ticamente vistas de dibujo est\u00e1ndar, como ortogr\u00e1ficas e isom\u00e9tricas, al crear una hoja nueva.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/drawingviewnov2625.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9763 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/drawingviewnov2625.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/drawingviewnov2625.png 800w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/drawingviewnov2625-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/drawingviewnov2625-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/drawingviewnov2625-728x410.png 728w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\">7.<strong> Env\u00ede comentarios f\u00e1cilmente al equipo de I+D de xDesign<\/strong><\/p>\n<p>Ayude a dar forma al futuro de xDesign compartiendo r\u00e1pidamente sus ideas y aportando comentarios de mejora, garantizando as\u00ed un proceso de desarrollo m\u00e1s centrado en el usuario.<\/p>\n<p>Con el nuevo bot\u00f3n de comentarios, puede enviar ideas de mejora directamente al equipo de I+D de xDesign. Puede incluir su informaci\u00f3n de contacto si desea que nos pongamos en contacto con usted en relaci\u00f3n con su sugerencia.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/feedbacknov2625.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9764 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/feedbacknov2625.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/feedbacknov2625.png 800w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/feedbacknov2625-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/feedbacknov2625-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/feedbacknov2625-728x410.png 728w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\">8.<strong> A\u00f1ada un toque de color para mejorar la claridad del modelo <\/strong><\/p>\n<p>Aporte claridad y reduzca los errores de interpretaci\u00f3n asignando autom\u00e1ticamente colores distintos a cada nuevo conjunto de geometr\u00eda con una nueva opci\u00f3n en el men\u00fa Preferencias del usuario.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/colorassignmentxdesignnov725-2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9765 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/colorassignmentxdesignnov725-2.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/colorassignmentxdesignnov725-2.png 800w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/colorassignmentxdesignnov725-2-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/colorassignmentxdesignnov725-2-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/colorassignmentxdesignnov725-2-728x410.png 728w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\">9.<strong> Proteja los datos no guardados con el almacenamiento centralizado de datos y el guardado autom\u00e1tico<\/strong><\/p>\n<p>Evite perder el progreso en su trabajo gracias al guardado autom\u00e1tico, incluso si se produce una desconexi\u00f3n por fallos de conexi\u00f3n, tiempo de espera o errores inesperados.<\/p>\n<p>Adem\u00e1s, el contenido reciente y los puntos de restauraci\u00f3n autom\u00e1ticos ahora se almacenan de forma centralizada, lo que le permite retomar el trabajo desde cualquier sesi\u00f3n de xDesign.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/autosavenov2625.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9766 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/autosavenov2625.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/autosavenov2625.png 800w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/autosavenov2625-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/autosavenov2625-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/autosavenov2625-728x410.png 728w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\">10.<strong> Transforme im\u00e1genes de mecanismos en croquis 2D totalmente funcionales<\/strong><\/p>\n<p>Convierta una imagen de un mecanismo en un croquis param\u00e9trico con la opci\u00f3n Mecanismo 2D de la herramienta Imagen a croquis.<\/p>\n<p>El mecanismo se convierte en un croquis totalmente restringido al reconocer objetos en la imagen (v\u00ednculos, posiciones, rodillos, etc.) y restricciones (bisagras, controles deslizantes, puntos de posici\u00f3n, etc.).<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/mechanismtosketchnov2625.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9767 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/mechanismtosketchnov2625.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/mechanismtosketchnov2625.png 800w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/mechanismtosketchnov2625-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/mechanismtosketchnov2625-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/mechanismtosketchnov2625-728x410.png 728w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1Y eso es todo! Nuestras 10 funciones principales de este a\u00f1o. \u00bfQu\u00e9 le parece? Trasl\u00e1denos su opini\u00f3n y d\u00edganos qu\u00e9 le gustar\u00eda que a\u00f1adi\u00e9ramos con el nuevo bot\u00f3n Comentarios.<\/p>\n<p>Vuelva a consultar estas mejoras cuando desee. <a href=\"https:\/\/www.solidworks.com\/es\/media\/solidworks-xdesign-2026-top-features\">Descargue el folleto<\/a>. Para obtener m\u00e1s informaci\u00f3n sobre las novedades de xDesign, visite <a href=\"https:\/\/www.solidworks.com\/es\/product\/whats-new-solidworks-xdesign\">este sitio web<\/a>. Y recuerde: \u00a1SOLIDWORKS 2026 ya est\u00e1 aqu\u00ed! Consulte las novedades en <a href=\"https:\/\/www.solidworks.com\/es\/product\/whats-new\">https:\/\/www.solidworks.com\/es\/product\/whats-new<\/a>.<\/p>\n<p>\u00a1Felices fiestas!<\/p>\n<p>\u00a1Hasta el a\u00f1o que viene! Si planea visitar <a href=\"https:\/\/www.3dexperienceworld.com\/?_gl=1*1k0pf1s*_up*MQ..*_gs*MQ..*_ga*MTYyMjg1NzAwOS4xNzY0MTc0Njk4*_ga_TPGKGE8GTG*czE3NjQxNzQ2OTckbzEkZzAkdDE3NjQxNzQ2OTkkajYwJGwwJGgw*_ga_9M7WCXDL10*czE3NjQxNzQ2OTckbzEkZzEkdDE3NjQxNzQ2OTkkajYwJGwwJGgw*_gcl_aw*R0NMLjE3NjQxNzQ3MDAuQ2p3S0NBaUE1NXJKQmhCeUVpd0FGa1kxUUJRLVg5Q3pFZ0NSMHlTR01fRlUtTFp2bU5FTUpONFRURnc4SjJGaVBNRkx3V0ZfNWJOdmRob0M0UDRRQXZEX0J3RQ..*_gcl_au*NDA3MjczMDg4LjE3NjQxNzQ2OTk.&amp;gclid=CjwKCAiA55rJBhByEiwAFkY1QBQ-X9CzEgCR0ySGM_FU-LZvmNEMJN4TTFw8J2FiPMFLwWF_5bNvdhoC4P4QAvD_BwE&amp;gbraid=0AAAAADqOeJRE-KEQs96ya6B44eHD2K7Lf\"><strong><span style=\"color: windowtext;text-decoration: none\">3D<\/span><\/strong>EXPERIENCE World<\/a> en 2026, estar\u00e9 disponible para hablar de todo lo relacionado con xApps junto con algunos de mis estimados compa\u00f1eros el martes 3 de febrero en el Web Browser Power Hour a las 17:00\u00a0CST, durante el Mega Meetup. \u00a1Espero verle por all\u00ed!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ahora que 2025 est\u00e1 llegando a su fin, me gustar\u00eda compartir algunas de las principales mejoras que se han incorporado este a\u00f1o a su soluci\u00f3n basada en navegador favorita: SOLIDWORKS xDesign. Para empezar, es a\u00fan m\u00e1s f\u00e1cil acceder a todas<\/p>\n... <a href=\"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/solidworks-blog\/3dexperience\/las-10-caracteristicas-principales-de-solidworks-xdesign-en-2025\/\">Continuado<\/a>","protected":false},"author":418,"featured_media":9772,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"","_yoast_wpseo_metadesc":"","footnotes":""},"categories":[423,1470,1450,947,787,1485,316],"tags":[1486,1487,1488,1489,1490,1491,1492,1493,1494,70],"class_list":["post-9757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3dexperience","category-client","category-cloud-services","category-colaboracion","category-diseno","category-solidworks-2","category-solidworks-xdesign","tag-autosave","tag-convert-image-to-sketch","tag-exploded-vies","tag-extender-reality-vr-and-ar-settings","tag-generative-drawings","tag-parametric-modeling","tag-product-definition","tag-solidworks-browser-based-design","tag-subdivision-modeling","tag-xdesign"],"acf":[],"_links":{"self":[{"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/posts\/9757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/users\/418"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/comments?post=9757"}],"version-history":[{"count":3,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/posts\/9757\/revisions"}],"predecessor-version":[{"id":9771,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/posts\/9757\/revisions\/9771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/media\/9772"}],"wp:attachment":[{"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/media?parent=9757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/categories?post=9757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/tags?post=9757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}