{"id":9742,"date":"2026-01-23T10:56:13","date_gmt":"2026-01-23T09:56:13","guid":{"rendered":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/?p=9742"},"modified":"2026-01-26T09:35:24","modified_gmt":"2026-01-26T08:35:24","slug":"novedades-de-draftsight-2026","status":"publish","type":"post","link":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/solidworks-blog\/draftsight\/novedades-de-draftsight-2026\/","title":{"rendered":"Novedades de DraftSight 2026"},"content":{"rendered":"<p>En el mundo digital actual, los dibujos siguen siendo un recurso de gran valor para comunicar la intenci\u00f3n de dise\u00f1o dentro de los procesos de trabajo de dise\u00f1o e ingenier\u00eda. Desde su lanzamiento en 2009, el <a href=\"https:\/\/www.draftsight.com\/es\">software de dise\u00f1o DraftSight<\/a> se ha consolidado como una soluci\u00f3n fiable para el dibujo 2D y contin\u00faa siendo una de las principales opciones del mercado. DraftSight 2026 eleva el list\u00f3n con una nueva pesta\u00f1a de p\u00e1gina de inicio, ventanas flotantes, el nuevo m\u00f3dulo BIM y muchas m\u00e1s funciones pensadas para optimizar el tiempo dedicado a los dibujos y reforzar la colaboraci\u00f3n con su equipo y las partes interesadas.<\/p>\n<p>Es un placer presentar las principales mejoras de DraftSight 2026, disponibles este mes de noviembre. Estas mejoras se aplican a todas las versiones de DraftSight para escritorio y a las funciones de DraftSight conectadas a la plataforma <strong>3D<\/strong>EXPERIENCE, salvo que se indique lo contrario.<\/p>\n<ol>\n<li><strong> M\u00f3dulo BIM: mejore la comunicaci\u00f3n entre los equipos de dise\u00f1o y construcci\u00f3n.<\/strong><\/li>\n<\/ol>\n<p>Abra f\u00e1cilmente modelos BIM 3D con el nuevo <a href=\"https:\/\/www.draftsight.com\/es\/2d-cad\/bim-module\">m\u00f3dulo BIM<\/a>, que le permite integrar flujos de trabajo BIM en procesos de dise\u00f1o basados en DWG y generar dibujos 2D importando y aprovechando los datos de archivos BIM 3D. As\u00ed podr\u00e1, por ejemplo, crear dibujos de planta, secciones y alzados a partir de modelos BIM en formatos como RVT e IFC.<\/p>\n<p>Este m\u00f3dulo garantiza la compatibilidad con archivos est\u00e1ndar del sector, lo que facilita a los profesionales de la arquitectura, ingenier\u00eda y construcci\u00f3n (AEC) colaborar y trabajar con un amplio abanico de herramientas. Importe e intercambie datos DWG entre DraftSight y las principales soluciones BIM, de modo que arquitectos, ingenieros y dise\u00f1adores puedan mantener un proceso de trabajo m\u00e1s coherente entre plataformas.<\/p>\n<p>Esta integraci\u00f3n mejora la colaboraci\u00f3n en los proyectos, aumenta la precisi\u00f3n del dise\u00f1o y optimiza la eficiencia global de los proyectos.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9743 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture1.png\" alt=\"\" width=\"1430\" height=\"804\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture1.png 1430w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture1-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture1-1024x576.png 1024w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture1-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture1-728x409.png 728w\" sizes=\"auto, (max-width: 1430px) 100vw, 1430px\" \/><\/a><\/p>\n<p><em>Disponible exclusivamente en DraftSight Premium (en las carteras de SOLIDWORKS Public Cloud y SOLIDWORKS Desktop), DraftSight Enterprise Plus y Collaborative Designer for DraftSight. <\/em><\/p>\n<ol start=\"2\">\n<li><strong> Administrador de conjunto de hojas en la plataforma: estandarice la documentaci\u00f3n del proyecto y simplifique la publicaci\u00f3n.<\/strong><\/li>\n<\/ol>\n<p>El Administrador de conjunto de hojas en la plataforma <strong>3D<\/strong>EXPERIENCE lleva la gesti\u00f3n de dibujos 2D a un nuevo nivel al integrar las herramientas CAD de DraftSight con la plataforma. El resultado es un entorno m\u00e1s eficiente, con datos coherentes, colaboraci\u00f3n fluida y capacidad de ampliaci\u00f3n. Se trata de un paso estrat\u00e9gico hacia una ingenier\u00eda moderna y conectada. Para las empresas que buscan optimizar sus procesos de trabajo en 2D, esta soluci\u00f3n marca un camino claro hacia una mayor eficiencia y control.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9744 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture2.png\" alt=\"\" width=\"780\" height=\"439\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture2.png 780w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture2-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture2-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture2-728x410.png 728w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/a><\/p>\n<p>Centralice los archivos de datos de conjuntos de hojas (DST) en 3DSpace para habilitar la colaboraci\u00f3n en tiempo real, la organizaci\u00f3n automatizada de hojas y la publicaci\u00f3n simplificada en marcadores. DraftSight permite crear archivos DST y guardarlos directamente en marcadores. Despu\u00e9s, puede abrirlos desde ese mismo espacio.<\/p>\n<p>Tambi\u00e9n puede definir las propiedades del Administrador de conjunto de hojas, como el nombre del proyecto, los datos del cliente, los campos de los bloques de t\u00edtulo y otros par\u00e1metros. Los archivos DST pueden crearse a partir de un dibujo existente o mediante una plantilla de hoja de dibujo. DraftSight genera los archivos DST como objetos PLM.<\/p>\n<p>Esta funci\u00f3n mejora la gesti\u00f3n de archivos DST en el Administrador de conjunto de hojas gracias a una integraci\u00f3n m\u00e1s s\u00f3lida en los espacios de colaboraci\u00f3n.<\/p>\n<p><em>Disponible solo en DraftSight Premium, DraftSight Mechanical y Collaborative Designer for DraftSight (los tres est\u00e1n incluidos en la cartera de SOLIDWORKS Public Cloud). <\/em><\/p>\n<ol start=\"3\">\n<li><strong> Impresi\u00f3n por lotes de archivos en espacios de colaboraci\u00f3n: ahorre tiempo y simplifique la impresi\u00f3n.<\/strong><\/li>\n<\/ol>\n<p>Ahora es posible imprimir por lotes archivos y carpetas DWG directamente desde la plataforma <strong>3D<\/strong>EXPERIENCE, dentro de su espacio de colaboraci\u00f3n. Solo tiene que acceder a Imprimir, Impresi\u00f3n por lotes, seleccionar el archivo o la carpeta y continuar con el proceso.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9745 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture3.png\" alt=\"\" width=\"780\" height=\"439\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture3.png 780w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture3-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture3-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture3-728x410.png 728w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/a><\/p>\n<p>Esta mejora automatiza la impresi\u00f3n de varios dibujos y hojas CAD en una \u00fanica operaci\u00f3n, lo que reduce el trabajo manual, acorta los tiempos de procesamiento y minimiza los errores, para que pueda compartir sus conjuntos de dibujos con mayor agilidad durante las revisiones.<\/p>\n<p><em>Disponible solo en DraftSight Premium, DraftSight Mechanical y Collaborative Designer for DraftSight (los tres est\u00e1n incluidos en la cartera de SOLIDWORKS Public Cloud). <\/em><\/p>\n<ol start=\"4\">\n<li><strong> Ventanas de documentos flotantes: mayor productividad al trabajar con varios monitores.<\/strong><\/li>\n<\/ol>\n<p>Aumente la productividad en configuraciones de varios monitores separando las pesta\u00f1as de dibujo en ventanas independientes y m\u00f3viles. Las ventanas de documentos flotantes permiten abrir dibujos en ventanas independientes fuera de la aplicaci\u00f3n principal en DraftSight, lo que permite visualizar f\u00e1cilmente varios dibujos en paralelo o en distintos monitores.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture4.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9746 \" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture4.png\" alt=\"\" width=\"681\" height=\"383\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture4.png 624w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture4-300x169.png 300w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/><\/a><\/p>\n<p>El trabajo con varios monitores y la visualizaci\u00f3n de dibujos en paralelo facilita la copia, el pegado y la gesti\u00f3n simult\u00e1nea de diferentes proyectos y aumenta la productividad.<\/p>\n<p><em>Disponible \u00fanicamente en DraftSight Premium, DraftSight Mechanical (en las carteras de SOLIDWORKS Public Cloud y SOLIDWORKS Desktop), DraftSight Enterprise Plus y Collaborative Designer for DraftSight.<\/em><\/p>\n<ol start=\"5\">\n<li><strong> Centro de inicio centralizado: acceso m\u00e1s r\u00e1pido a proyectos, archivos recientes y recursos.<\/strong><\/li>\n<\/ol>\n<p>Agilice sus tareas con la nueva pesta\u00f1a P\u00e1gina de inicio. Al abrir DraftSight, encontrar\u00e1 una pesta\u00f1a que ofrece acceso directo a los archivos recientes, a la configuraci\u00f3n del espacio de trabajo y a los recursos de aprendizaje.<\/p>\n<p>La pesta\u00f1a P\u00e1gina de inicio centraliza las operaciones esenciales y ofrece una experiencia de usuario m\u00e1s fluida al iniciar DraftSight, al proporcionar en un \u00fanico lugar acceso r\u00e1pido a las funciones que utiliza con mayor frecuencia.<\/p>\n<p>[nueva imagen de p\u00e1gina de inicio]<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture5.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9747 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture5.png\" alt=\"\" width=\"1430\" height=\"804\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture5.png 1430w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture5-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture5-1024x576.png 1024w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture5-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture5-728x409.png 728w\" sizes=\"auto, (max-width: 1430px) 100vw, 1430px\" \/><\/a><\/p>\n<p><em>Disponible \u00fanicamente en DraftSight Premium, DraftSight Mechanical (en las carteras de SOLIDWORKS Public Cloud y SOLIDWORKS Desktop), DraftSight Enterprise Plus y Collaborative Designer for DraftSight.<\/em><\/p>\n<ol start=\"6\">\n<li><strong> Contenido mejorado en las pesta\u00f1as de la cinta: encuentre comandos de forma m\u00e1s f\u00e1cil y r\u00e1pida.<\/strong><\/li>\n<\/ol>\n<p>DraftSight incorpora una cinta de opciones m\u00e1s clara y mejor organizada, que mejora la usabilidad gracias a un acceso m\u00e1s directo a los comandos y a entornos de trabajo familiares y personalizables.<\/p>\n<p>Entre las opciones de personalizaci\u00f3n del espacio de trabajo se incluyen \u00abCAD General\u00bb y versiones mejoradas de \u00abBorradores y anotaci\u00f3n\u00bb.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture6.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9748 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture6.png\" alt=\"\" width=\"624\" height=\"351\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture6.png 624w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture6-300x169.png 300w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/a><\/p>\n<p><em>Disponible \u00fanicamente en DraftSight Premium, DraftSight Mechanical (en las carteras de SOLIDWORKS Public Cloud y SOLIDWORKS Desktop), DraftSight Enterprise Plus y Collaborative Designer for DraftSight.<\/em><\/p>\n<ol start=\"7\">\n<li><strong> Mejoras en el comando EXTRACCI\u00d3N DE DATOS: reduzca el trabajo manual y minimice los errores en la extracci\u00f3n de datos.<\/strong><\/li>\n<\/ol>\n<p>Aumente la eficacia de la extracci\u00f3n de datos en DraftSight con encabezados CSV que facilitan la interpretaci\u00f3n de las exportaciones, columnas de f\u00f3rmulas integradas para realizar c\u00e1lculos personalizados y la posibilidad de obtener datos brutos, procesados y calculados en un \u00fanico paso, lo que reduce el trabajo manual y agiliza la integraci\u00f3n con otras aplicaciones.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture7.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9749 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture7.png\" alt=\"\" width=\"1430\" height=\"804\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture7.png 1430w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture7-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture7-1024x576.png 1024w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture7-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture7-728x409.png 728w\" sizes=\"auto, (max-width: 1430px) 100vw, 1430px\" \/><\/a><\/p>\n<ol start=\"8\">\n<li><strong> Comando de campo: Aumente la compatibilidad con las expresiones DIESEL: automatice el texto din\u00e1mico y los c\u00e1lculos en los dibujos.<\/strong><\/li>\n<\/ol>\n<p>El comando Campo incorpora ahora expresiones DIESEL, que permiten generar texto din\u00e1mico que se actualiza autom\u00e1ticamente en funci\u00f3n de las propiedades del dibujo o de las entradas del usuario.<\/p>\n<p>De este modo, podr\u00e1 crear dibujos inteligentes que se mantienen actualizados de forma autom\u00e1tica cuando cambian sus propiedades, lo que reduce las actualizaciones manuales y el riesgo de disponer de informaci\u00f3n desfasada.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture8.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9750 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture8.png\" alt=\"\" width=\"624\" height=\"351\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture8.png 624w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture8-300x169.png 300w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/a><\/p>\n<ol start=\"9\">\n<li><strong> Paneles de vista redimensionables en el espacio del modelo: mejore el trabajo simult\u00e1neo y la navegaci\u00f3n en paralelo.<\/strong><\/li>\n<\/ol>\n<p>Mejore los procesos multitarea en su flujo de trabajo de CAD con mosaicos de vista ajustables que le permiten ver y navegar simult\u00e1neamente de forma eficiente por varias \u00e1reas del modelo mediante un ajuste de tama\u00f1o y alineaci\u00f3n intuitivos.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture9.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9751 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture9.png\" alt=\"\" width=\"624\" height=\"351\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture9.png 624w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture9-300x169.png 300w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/a><\/p>\n<p><em>Disponible \u00fanicamente en DraftSight Premium, DraftSight Mechanical (en las carteras de SOLIDWORKS Public Cloud y SOLIDWORKS Desktop), DraftSight Enterprise Plus y Collaborative Designer for DraftSight.<\/em><\/p>\n<ol start=\"10\">\n<li><strong> Archivos que pueden adjuntarse desde la plataforma 3DEXPERIENCE: mejore la colaboraci\u00f3n y la productividad.<\/strong><\/li>\n<\/ol>\n<p>La pesta\u00f1a Adjuntar herramienta incorpora una nueva funci\u00f3n, \u00abAdjuntar desde <strong>3D<\/strong>EXPERIENCE\u00bb, que permite a\u00f1adir archivos DWG, PDF, DNG y PNG directamente desde la plataforma <strong>3D<\/strong>EXPERIENCE. Esta opci\u00f3n tambi\u00e9n est\u00e1 disponible en la paleta Referencia, donde puede seleccionarse \u00abAdjuntar desde <strong>3D<\/strong>EXPERIENCE\u00bb en el men\u00fa desplegable.<\/p>\n<p>Simplifique el proceso al adjuntar archivos directamente desde la plataforma <strong>3D<\/strong>EXPERIENCE. Ahorre tiempo, reduzca los errores y mejore la eficiencia y la colaboraci\u00f3n del dise\u00f1o.<\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture10.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9752 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture10.png\" alt=\"\" width=\"780\" height=\"439\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture10.png 780w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture10-300x169.png 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture10-768x432.png 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Picture10-728x410.png 728w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/a><\/p>\n<p><em>Disponible solo en DraftSight Premium, DraftSight Mechanical y Collaborative Designer for DraftSight (los tres est\u00e1n incluidos en la cartera de SOLIDWORKS Public Cloud). <\/em><\/p>\n<p>Estas son las principales caracter\u00edsticas de DraftSight 2026. Recuerde que muchas de estas mejoras se han ido incorporando en entregas funcionales a lo largo de 2025 y ya se encuentran disponibles. Descargue el folleto de las 10 principales <a href=\"https:\/\/www.solidworks.com\/es\/media\/draftsight-2026-top-10-features\">aqu\u00ed<\/a>.<\/p>\n<p>Acceda a m\u00e1s recursos de DraftSight 2026 y descubra las novedades de otras soluciones de SOLIDWORKS en: <a href=\"https:\/\/www.solidworks.com\/es\/product\/whats-new\"><strong>https:\/\/www.solidworks.com\/es\/product\/whats-new<\/strong><\/a><strong>.<\/strong><\/p>\n<p><a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Generic-visit-draftsightdotcom.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9753 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Generic-visit-draftsightdotcom.jpg\" alt=\"\" width=\"1200\" height=\"628\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Generic-visit-draftsightdotcom.jpg 1200w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Generic-visit-draftsightdotcom-300x157.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Generic-visit-draftsightdotcom-1024x536.jpg 1024w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Generic-visit-draftsightdotcom-768x402.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/15\/2026\/01\/Generic-visit-draftsightdotcom-728x381.jpg 728w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el mundo digital actual, los dibujos siguen siendo un recurso de gran valor para comunicar la intenci\u00f3n de dise\u00f1o dentro de los procesos de trabajo de dise\u00f1o e ingenier\u00eda. Desde su lanzamiento en 2009, el software de dise\u00f1o DraftSight<\/p>\n... <a href=\"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/solidworks-blog\/draftsight\/novedades-de-draftsight-2026\/\">Continuado<\/a>","protected":false},"author":418,"featured_media":9754,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"","_yoast_wpseo_metadesc":"","footnotes":""},"categories":[423,1442,385,21,1481,1465,49,1476],"tags":[63,568,1475,26],"class_list":["post-9742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3dexperience","category-draftsight","category-edrawings","category-gestion-de-datos","category-solidworks-2026","category-solidworks-for-makers","category-solidworks_manage","category-whats-new-2026","tag-3dexperience","tag-draftsight","tag-novedades-solidworks-2026","tag-solidworks"],"acf":[],"_links":{"self":[{"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/posts\/9742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/users\/418"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/comments?post=9742"}],"version-history":[{"count":2,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/posts\/9742\/revisions"}],"predecessor-version":[{"id":9756,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/posts\/9742\/revisions\/9756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/media\/9754"}],"wp:attachment":[{"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/media?parent=9742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/categories?post=9742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworkslatamyesp\/wp-json\/wp\/v2\/tags?post=9742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}