{"id":25477,"date":"2025-07-28T09:00:27","date_gmt":"2025-07-28T07:00:27","guid":{"rendered":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/?p=25477"},"modified":"2025-07-14T15:24:12","modified_gmt":"2025-07-14T13:24:12","slug":"mps-verkurzt-simulationszeiten-von-zwei-wochen-auf-einen-tag-mit-3dexperince-works-simulation","status":"publish","type":"post","link":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2025\/07\/mps-verkurzt-simulationszeiten-von-zwei-wochen-auf-einen-tag-mit-3dexperince-works-simulation.html","title":{"rendered":"MPS verk\u00fcrzt Simulationszeiten von zwei Wochen auf einen Tag mit <b>3D<\/b>EXPERINCE Works Simulation"},"content":{"rendered":"<h2>Einblicke in die Digitalisierung eines f\u00fchrenden Automobilzulieferers<\/h2>\n<p><a href=\"http:\/\/www.morganpolymerseals.com\" target=\"_blank\" rel=\"noopener\">Morgan Polymer Seals<\/a> (MPS) wurde 1997 von Kevin Morgan gegr\u00fcndet und nutzt seit vielen Jahren <a href=\"https:\/\/www.solidworks.com\/de\" target=\"_blank\" rel=\"noopener\">SOLIDWORKS\u00ae<\/a>, um Dichtungskonzepte, Konstruktionen und Werkzeuge zu entwickeln und Konstruktionsdaten mit Kunden und Partnern auszutauschen.<\/p>\n<p>Angesichts des rasanten Wachstums des Marktes f\u00fcr Elektrofahrzeuge (EVs) und Hybridfahrzeuge stand MPS vor einer entscheidenden Frage: Wie lassen sich die wachsenden Anforderungen an Produktentwicklung, Simulation und Kundenbetreuung effizient und zukunftssicher umsetzen?<\/p>\n<p>Die Antwort lag in der internen Umsetzung komplexer Finite-Elemente-Analysen (FEA), um Effizienz zu steigern und Kosten zu senken \u2013 unterst\u00fctzt durch das cloudbasierte <a href=\"https:\/\/www.solidworks.com\/de\/3dexperience-works\" target=\"_blank\" rel=\"noopener\"><strong>3D<\/strong>EXPERIENCE Works<\/a> Portfolio von Dassault Syst\u00e8mes und die darin integrierte Simulationsl\u00f6sung Structural Mechanics Engineer.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25480 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/morganpolymerseals_bannerimg_1-e1750238667596.jpg\" alt=\"\" width=\"1220\" height=\"566\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/morganpolymerseals_bannerimg_1-e1750238667596.jpg 1220w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/morganpolymerseals_bannerimg_1-e1750238667596-300x139.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/morganpolymerseals_bannerimg_1-e1750238667596-615x285.jpg 615w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/morganpolymerseals_bannerimg_1-e1750238667596-768x356.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/morganpolymerseals_bannerimg_1-e1750238667596-728x338.jpg 728w\" sizes=\"auto, (max-width: 1220px) 100vw, 1220px\" \/><\/p>\n<h2>Die Herausforderung: Mehr Simulation, weniger Zeit<\/h2>\n<p>Als Hersteller von \u00fcber 100 Millionen kundenspezifischen Dichtungen j\u00e4hrlich beliefert MPS OEMs und Tier-1-Lieferanten weltweit \u2013 unter anderem Ford, GM, Nissan und Hyundai. Mit der steigenden Nachfrage nach EVs wurde schnell klar: Konventionelle Prozesse und externe FEA-Dienstleister reichen nicht mehr aus.<\/p>\n<p>Denn: EVs erfordern f\u00fcr jede elektrische Verbindung eine Dichtung \u2013 eine v\u00f6llig neue Dimension des Abdichtens, verglichen mit klassischen Verbrennungsmotoren.<\/p>\n<h2>Die L\u00f6sung: Simulation aus der Cloud<\/h2>\n<p>Durch den Einsatz des Structural Mechanics Engineer (SME) aus dem <strong>3D<\/strong>EXPERIENCE Works Portfolio konnte MPS:<\/p>\n<ul>\n<li>Simulationen f\u00fcr Hyperelastizit\u00e4t, Kriechen, Erm\u00fcdung und Kontakt intern abbilden<\/li>\n<li>die Simulationszeit von 14 Tagen auf nur einen Tag reduzieren<\/li>\n<li>s\u00e4mtliche Rechenleistung in die Cloud auslagern \u2013 ohne zus\u00e4tzliche Hardwareinvestitionen<\/li>\n<li>remote arbeitende Teams in den USA mit der Fertigung in Mexiko vernetzen<\/li>\n<\/ul>\n<p>Besonders \u00fcberzeugt hat MPS der integrierte Abaqus Explicit Solver, der optimal f\u00fcr komplexe Materialverhalten geeignet ist.<\/p>\n<p>Zwei Anwendungsbereiche stechen hervor:<\/p>\n<ul>\n<li>Kundenspezifische Anwendungssimulation \u2013 schneller Proof-of-Concept f\u00fcr OEMs<\/li>\n<li>Materialforschung &amp; Neuentwicklung \u2013 beschleunigte Iterationen durch Cloud-Rechenleistung<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25481 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img1.jpg\" alt=\"\" width=\"863\" height=\"650\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img1.jpg 863w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img1-300x226.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img1-615x463.jpg 615w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img1-768x578.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img1-728x548.jpg 728w\" sizes=\"auto, (max-width: 863px) 100vw, 863px\" \/><\/p>\n<h2>Mehr als nur Technologie: Zusammenarbeit im Fokus<\/h2>\n<p>Die Einf\u00fchrung von <strong>3D<\/strong>EXPERIENCE Works hat auch die Kooperation mit Kunden intensiviert. Simulationen von Einsteckkr\u00e4ften, Dichtverhalten und Designkonzepten flie\u00dfen fr\u00fchzeitig in gemeinsame Projekte ein. So wird MPS vom klassischen Zulieferer zum Entwicklungspartner.<\/p>\n<h2>Cloud als Wachstumsstrategie<\/h2>\n<p>Mit der Entscheidung f\u00fcr Cloud-Simulation verfolgt MPS eine klare digitale Agenda:<\/p>\n<ul>\n<li>Keine teuren lokalen Workstations notwendig<\/li>\n<li>Skalierbare Lizenzen je nach Bedarf<\/li>\n<li>Automatisierte Updates &amp; Wartung<\/li>\n<li>Vollst\u00e4ndige Integration mit bestehenden SOLIDWORKS Daten<\/li>\n<\/ul>\n<h2>Das Ergebnis: Mehr Innovation, weniger Reibung<\/h2>\n<ul>\n<li><strong>Kosteneffizienz<\/strong>: Durch Reduktion externer Dienstleistungen und Hardware<\/li>\n<li><strong>Zeitgewinn<\/strong>: FEA-Studien in Stunden statt Wochen<\/li>\n<li><strong>Wettbewerbsvorteil<\/strong>: Schnellere Marktreife neuer Produkte<\/li>\n<li><strong>Zukunftssicherheit<\/strong>: Plattform f\u00fcr skalierbares Wachstum im EV-Bereich<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25482 size-full\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img2.jpg\" alt=\"\" width=\"1227\" height=\"522\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img2.jpg 1227w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img2-300x128.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img2-615x262.jpg 615w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img2-768x327.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/MorganPolymerSeals_Img2-728x310.jpg 728w\" sizes=\"auto, (max-width: 1227px) 100vw, 1227px\" \/><\/p>\n<h2>Fazit<\/h2>\n<p>Morgan Polymer Seals zeigt eindrucksvoll, wie mittelst\u00e4ndische Industrieunternehmen mit der richtigen Technologieplattform auf globale Marktver\u00e4nderungen reagieren \u2013 und gleichzeitig interne Effizienz, Kundenn\u00e4he und Innovationskraft st\u00e4rken. Ein besonders spannender Aspekt ist die geplante Erweiterung der <strong>3D<\/strong>EXPERIENCE Plattform bei MPS um umfassende <strong data-start=\"679\" data-end=\"703\">PLM-Funktionalit\u00e4ten<\/strong>. Ziel ist es, alle Konstruktions- und Engineering-Tools zuk\u00fcnftig auf einer zentralen, cloudbasierten Plattform zu konsolidieren.<\/p>\n<p>Die Cloud ist dabei nicht nur Mittel zum Zweck \u2013 sie ist der Enabler f\u00fcr eine neue Form der Produktentwicklung.<\/p>\n<table border=\"0\" width=\"100%\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td width=\"20px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-22072\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/doubleredarrow-8-10-1-2-3-2-1-2-1-1-3-1-1-4.png\" alt=\"\" width=\"15\" height=\"10\" \/><\/td>\n<td><strong><a href=\"https:\/\/www.solidworks.com\/de\/story\/morgan-polymer-seals\" target=\"_blank\" rel=\"noopener\">Zum Referenzbericht<\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Weitere interessante Referenzberichte:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2025\/04\/losungen-fur-die-zusammenarbeit-von-mensch-und-maschine-mit-solidworks.html\">ROSE Systemtechnik: L\u00f6sungen f\u00fcr die Zusammenarbeit von Mensch und Maschine mit SOLIDWORKS<\/a><\/li>\n<li><a href=\"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2025\/05\/alveri-intelligente-ladeinfrastruktur-fur-die-e-mobilitat-der-zukunft.html\" target=\"_blank\" rel=\"noopener\">Alveri \u2013 Intelligente Ladeinfrastruktur f\u00fcr die E-Mobilit\u00e4t der Zukunft<\/a><\/li>\n<li><a href=\"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2025\/04\/losungen-fur-die-zusammenarbeit-von-mensch-und-maschine-mit-solidworks.html\">ROSE Systemtechnik: L\u00f6sungen f\u00fcr die Zusammenarbeit von Mensch und Maschine mit SOLIDWORKS<\/a><\/li>\n<li><a href=\"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2025\/04\/kleine-originale-grose-prazision-wie-scaleart-mit-solidworks-beeindruckende-funktionsmodelle-erschafft.html\">Kleine Originale, gro\u00dfe Pr\u00e4zision: Wie ScaleART mit SOLIDWORKS beeindruckende Funktionsmodelle erschafft<\/a><\/li>\n<li><a href=\"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2025\/03\/geomed-optimierung-der-entwicklung-chirurgischer-und-dentaler-instrumente-mit-solidworks-und-3dexperience-works.html\">GEOMED \u2013 Optimierung der Entwicklung chirurgischer und dentaler Instrumente mit SOLIDWORKS und <strong>3D<\/strong>EXPERIENCE Works<\/a><\/li>\n<li><a href=\"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2024\/12\/kindgerechte-bewegung-mit-solidworks-und-3dexperience-plattform.html\">Kindgerechte Bewegung mit der <strong>3D<\/strong>EXPERIENCE Plattform<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Einblicke in die Digitalisierung eines f\u00fchrenden Automobilzulieferers Morgan Polymer Seals (MPS) wurde 1997 von Kevin Morgan gegr\u00fcndet und nutzt seit vielen Jahren SOLIDWORKS\u00ae, um Dichtungskonzepte, Konstruktionen und Werkzeuge zu entwickeln und Konstruktionsdaten mit Kunden und Partnern auszutauschen. Angesichts des rasanten<\/p>\n... <a href=\"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2025\/07\/mps-verkurzt-simulationszeiten-von-zwei-wochen-auf-einen-tag-mit-3dexperince-works-simulation.html\">Continued<\/a>","protected":false},"author":373,"featured_media":25481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"Cloud Simulation","_yoast_wpseo_metadesc":"Morgan Polymer Seals steigert mit SOLIDWORKS und der 3DEXPERIENCE Plattform die Effizienz und setzt konsequent auf Cloud Simulation.","footnotes":""},"categories":[1527,1362,422,505,35,45,274,2,1,2107],"tags":[1505,1949,4688,440,450,4687,74,4686,4685,658,3133,335,176,7,1950],"class_list":["post-25477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3dexperience-loesungen","category-cloud","category-konstruktion","category-kundenerfolg-kundenreferenz-case-study","category-produktdatenmanagement","category-simulation","category-solidworks","category-solidworks-simulation","category-themenuebergreifend","category-zusammenarbeit-kollaboration","tag-3dexperience-works","tag-abaqus","tag-abaqus-explicit-solver","tag-cloud","tag-fea","tag-finite-elemente-analysen","tag-konstruktion","tag-morgan-polymer-seals","tag-mps","tag-plm","tag-product-lifecycle-management","tag-simulation","tag-sme","tag-solidworks","tag-structural-mechanics-engineer"],"acf":[],"_links":{"self":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/25477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/users\/373"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/comments?post=25477"}],"version-history":[{"count":12,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/25477\/revisions"}],"predecessor-version":[{"id":25540,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/25477\/revisions\/25540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/media\/25481"}],"wp:attachment":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/media?parent=25477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/categories?post=25477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/tags?post=25477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}