{"id":24525,"date":"2024-11-28T09:00:59","date_gmt":"2024-11-28T08:00:59","guid":{"rendered":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/?p=24525"},"modified":"2024-11-26T13:27:54","modified_gmt":"2024-11-26T12:27:54","slug":"behlen-optimiert-seine-produktionsanlage-virtuell-mit-factory-simulation-engineer","status":"publish","type":"post","link":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2024\/11\/behlen-optimiert-seine-produktionsanlage-virtuell-mit-factory-simulation-engineer.html","title":{"rendered":"Behlen optimiert seine Produktionsanlage virtuell mit Factory Simulation Engineer"},"content":{"rendered":"<p>Behlen Mfg. Co., ein weltweit f\u00fchrender Metallhersteller mit \u00fcber 1.100 Mitarbeitern, wurde 1936 in einer Garage in Columbus, Nebraska, gegr\u00fcndet. Drei der unterschiedlichen Gesch\u00e4ftsbereiche von Behlen sind in der Fertigungs-, Produktions- und Montageanlage in Columbus angesiedelt. Dazu geh\u00f6ren Behlen Country, der f\u00fchrende US-Hersteller von Viehzuchtausr\u00fcstung, Behlen Building Systems, ein Hersteller hochwertiger Metallbausysteme, und der Gesch\u00e4ftsbereich International and Diversified Products, der aus Behlen Grain Systems, Behlen Joiners (hydraulische Pressen) und Behlen Custom Fabrication besteht.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/behlen-plant2-1.jpg\" width=\"800\" height=\"349\" \/><\/p>\n<p>Da die riesige Fabrik in Columbus seit \u00fcber 80 Jahren in Betrieb ist, \u00fcberschneiden sich die Produktionslinien und -prozesse der verschiedenen Gesch\u00e4ftsbereiche, was zu einem Ansammlung alter, neuer und ma\u00dfgefertigter Ger\u00e4te f\u00fchrt \u2013 einige davon werden noch verwendet, andere nicht. Au\u00dferdem gibt es verschiedene Materialien sowie eine Vielzahl an M\u00f6beln, Schr\u00e4nken und Lagerregalen. Im Laufe der Jahre hat jeder Gesch\u00e4ftsbereich jeden verf\u00fcgbaren Platz eingenommen, was zu Engp\u00e4ssen gef\u00fchrt hat, die den Fabrikfluss behindern.<\/p>\n<p>\u201eUnsere Werksaufteilung ist zu einem Sammelsurium geworden, bei dem bestimmte Auftr\u00e4ge von einem Ende des Geb\u00e4udes zum anderen verschoben werden, obwohl sie von einem besseren Ablauf innerhalb der Werksaufteilung h\u00e4tten profitieren k\u00f6nnen\u201c, erkl\u00e4rt Prozessingenieur James Kucera. \u201eDas ultimative Ziel ist es, die Anlage so zu konfigurieren, dass bessere Produkte zu geringeren Kosten hergestellt werden k\u00f6nnen.\u201c<\/p>\n<h2><strong>Verbesserung der betrieblichen Effizienz<\/strong><\/h2>\n<p>Nach intensiver Suche investierte Behlen in den cloudbasierten\u00a0<a href=\"https:\/\/www.solidworks.com\/de\/media\/expand-horizons-factory-simulation-3dexperience-works-2023\" target=\"_blank\" rel=\"noopener\">Factory Simulation Engineer<\/a>,\u00a0der Teil des\u00a0<strong>3D<\/strong>EXPERIENCE\u00ae Works Manufacturing-L\u00f6sungsportfolios ist. Die Fabriksimulation bietet Behlen die M\u00f6glichkeit, mehrere Produktionsszenarien in 2D-, 3D- oder Punktwolkenumgebungen zu analysieren und liefert eine 3D-Visualisierung der Anlage, um Problembereiche zu diagnostizieren und die Leistung zu verbessern.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/screenshot202023-06-2220074122-2.png\" width=\"800\" height=\"433\" \/><\/p>\n<p>Behlen scannte seine gesamte Fabrik mit 84.000 Quadratmetern Fl\u00e4che innerhalb einer Woche und produzierte \u00fcber drei Milliarden Cloud-Datenpunkte, aus denen ein virtuelles Modell erstellt wurde. Die Daten werden in 6 x 8 Fu\u00df gro\u00dfe Rasterabschnitte unterteilt, die alles in der Fabrik modellieren, von F\u00f6rderb\u00e4ndern bis zu M\u00fclleimern. Factory Simulation Engineer bietet eine Datengranularit\u00e4t von bis zu 1\/16 Zoll f\u00fcr jedes Element, sodass sich die genauen Auswirkungen potenzieller Konfigurations\u00e4nderungen leicht visualisieren lassen.<\/p>\n<p>Behlen hat mithilfe des Factory Simulation Engineer den Grundstein f\u00fcr die Koordinierung vieler Lean-Manufacturing-Ans\u00e4tze intelligenter Fabriken gelegt. Behlen wird die L\u00f6sung nutzen, um Material, Prozesse und andere Arbeitsabl\u00e4ufe zu bewerten und so die Standardisierung, Effizienz und Zusammenarbeit von Gesch\u00e4fts- und Entwicklungsgruppen in der gesamten Fabrik zu verbessern.<\/p>\n<h2><strong>Zusammenarbeit einfacher machen<\/strong><\/h2>\n<p>Mithilfe des cloudbasierten Produkts k\u00f6nnen die drei Gesch\u00e4ftseinheiten von Behlen h\u00e4ufiger und effektiver hinsichtlich R\u00e4umlichkeiten und Ausr\u00fcstung zusammenarbeiten. So k\u00f6nnen sie die Effizienz ihrer einzelnen Betriebsabl\u00e4ufe verbessern und potenzielle gemeinsame Gesch\u00e4ftsm\u00f6glichkeiten aufdecken, die zum Gesamterfolg von Behlen beitragen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/dual20robotic20welder20still20220copy-1.jpg\" width=\"800\" height=\"377\" \/><\/p>\n<p>\u201eWir sind nun in der Lage, den Gesch\u00e4ftsbereichen aufzuzeigen, wo es Gemeinsamkeiten zwischen ihren Maschinen, Ger\u00e4ten und Prozessen gibt und zu visualisieren, wie sich einzelne Ma\u00dfnahmen \u2013 etwa die Anschaffung neuer Ger\u00e4te oder die Entsorgung alter Ger\u00e4te \u2013 nicht nur auf ihre einzelnen Betriebsabl\u00e4ufe, sondern auf den gesamten Fabrikablauf auswirken\u201c, so Kucera abschlie\u00dfend.<\/p>\n<p>\u201eDies ist von entscheidender Bedeutung, um Lean-Prinzipien umzusetzen und sicherzustellen, dass eine Neukonfiguration sinnvoll ist. Beispielsweise kann eine Bewegung 20 damit verbundene Bewegungen nach sich ziehen. Mit Factory Simulation Engineer k\u00f6nnen wir alle damit verbundenen Bewegungen visualisieren und bessere Entscheidungen treffen sowie Situationen vermeiden, in denen wir zwei- oder dreimal neu konfigurieren m\u00fcssen, weil etwas \u00fcbersehen wurde.\u201c<\/p>\n<p>Wenn Sie weitere Informationen dazu w\u00fcnschen, wie Sie die Gestaltung Ihrer Produktionsanlage optimieren k\u00f6nnen, um die Betriebseffizienz zu steigern,\u00a0<a href=\"https:\/\/www.solidworks.com\/de\/how-to-buy\/find-solidworks-reseller\" target=\"_blank\" rel=\"noopener\">wenden Sie sich an Ihren Fachh\u00e4ndler vor Ort<\/a>\u00a0oder klicken Sie unten, um mehr dar\u00fcber zu erfahren, wie Sie noch heute mit der intelligenten Fertigung beginnen k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.solidworks.com\/lp\/how-start-your-smart-manufacturing-journey\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/sw_banner20iot20starter20guide20banners_961x25020-1.jpg\" alt=\"\" width=\"961\" height=\"250\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gro\u00dfer Fertigungs-, Produktions- und Montagehersteller nutzt 3DEXPERIENCE Works Factory Simulation Engineer zur Optimierung von Fabriklayouts, um bessere Produkte zu niedrigeren Kosten zu produzieren.<\/p>\n... <a href=\"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2024\/11\/behlen-optimiert-seine-produktionsanlage-virtuell-mit-factory-simulation-engineer.html\">Continued<\/a>","protected":false},"author":373,"featured_media":24523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"Behlen Factory Simulation Engineer","_yoast_wpseo_metadesc":"Erfahren Sie, wie Behlen seine Produktionsabl\u00e4ufe durch die Implementierung des Factory Simulation Engineer optimiert.","footnotes":""},"categories":[1527,1362,4291,422,505,274,642,1],"tags":[812,4427,3107,4428,646,1059,2082,4010,96,2015,109,3861,4325,3609,4006,4426,4007,4425,7,3715,3716],"class_list":["post-24525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3dexperience-loesungen","category-cloud","category-fertigung","category-konstruktion","category-kundenerfolg-kundenreferenz-case-study","category-solidworks","category-solidworks-cam","category-themenuebergreifend","tag-3dexperience","tag-3dexperience-works-factory-flow-engineer","tag-3dexperienceworks","tag-behlen","tag-cam","tag-cloud-computing","tag-collaboration","tag-customer-stories","tag-dassault-systemes","tag-delmia","tag-design","tag-fabrikautomation","tag-fabrikautomatisierung","tag-fabriklayout","tag-factory-automation","tag-factory-layout","tag-factory-simulation-engineer","tag-manufacturing-layout","tag-solidworks","tag-virtuelle-fabrikplanung","tag-virtuelle-fabriksimulation"],"acf":[],"_links":{"self":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/24525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/users\/373"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/comments?post=24525"}],"version-history":[{"count":5,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/24525\/revisions"}],"predecessor-version":[{"id":24530,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/24525\/revisions\/24530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/media\/24523"}],"wp:attachment":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/media?parent=24525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/categories?post=24525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/tags?post=24525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}