{"id":18366,"date":"2022-01-31T14:56:41","date_gmt":"2022-01-31T13:56:41","guid":{"rendered":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/?p=18366"},"modified":"2022-02-03T15:56:50","modified_gmt":"2022-02-03T14:56:50","slug":"spyra-water-guns-schon-laengst-keine-geheimwaffe-mehr-dank-solidworks-simulation","status":"publish","type":"post","link":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2022\/01\/spyra-water-guns-schon-laengst-keine-geheimwaffe-mehr-dank-solidworks-simulation.html","title":{"rendered":"Spyra Water Guns: Schon l\u00e4ngst keine Geheimwaffe mehr dank SOLIDWORKS Simulation"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18369\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/04_SpyraTwo_WaterBattle-300x200.jpg\" alt=\"Spyra Water Guns: Schon l\u00e4ngst keine Geheimwaffe mehr dank SOLIDWORKS Simulation\" width=\"563\" height=\"375\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/04_SpyraTwo_WaterBattle-300x200.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/04_SpyraTwo_WaterBattle-615x410.jpg 615w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/04_SpyraTwo_WaterBattle-768x512.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/04_SpyraTwo_WaterBattle-1536x1024.jpg 1536w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/04_SpyraTwo_WaterBattle-2048x1365.jpg 2048w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/04_SpyraTwo_WaterBattle-728x485.jpg 728w\" sizes=\"auto, (max-width: 563px) 100vw, 563px\" \/><\/p>\n<p>Sondern die wohl besten Wasserpistolen der Welt. Findet (nicht nur) CHIP in einem anschaulichen <strong><a href=\"https:\/\/www.chip.de\/news\/SpyraTwo-sorgt-fuer-epische-Wasserschlachten_183814845.html\">Praxistest<\/a> <\/strong>der bereits zweiten Generation: SpyraTwo. Der Trend geht ja schon l\u00e4nger zum gegenseitigen Beschie\u00dfen: ob per Paintball oder Laserpistolen. Wieso nicht auch mit Wasser? Dachten sich die Gr\u00fcnder von Spyra Water Guns \u2013 und machten sich ans Werk.<\/p>\n<p>Warum es so eine Pistole nicht schon l\u00e4ngst gab, fanden sie bald heraus. Der Teufel liegt wie oft im Detail: Bei zu viel Druck zerst\u00e4ubt das Wasser, bei zu wenig fliegt es nicht weit genug. Ein Jahr lang arbeitete das Spyra-Team an den technischen Problemen, befeuert durch das SOLIDWORKS Entrepreneurs Programm. 2018 schloss das Projekt SpyraOne auf Kickstarter als erfolgreichste deutsche Crowdfunding-Kampagne des Jahres. Wen wundert\u00b4s?<\/p>\n<h2><strong>Sie schie\u00dfen nur mit Wasser \u2013 aber kr\u00e4ftig<\/strong><\/h2>\n<p>Digitale Versionen klassischer Spielzeuge bringen oft nicht den Spa\u00df des Originals? Dass dem nicht so sein muss, beweist das Hightech-Spielzeug von Spyra. Das Gegenteil ist der Fall. Die Spyra Wasserpistole verbessert ihre analogen Vorg\u00e4nger auf so gut wie jede erdenkliche Weise.<\/p>\n<p>Gro\u00df und Klein werden deshalb lieber zur Spyra greifen. Kein Wunder, Leistung und Fun-Faktor sind hier enorm. Von so einer Wasserschlacht konnte man bisher nur tr\u00e4umen: Schussabgabe wie im 3D-Shooter, dabei viel Leistung und hohe Reichweite. Die Treffer sind am Gegner durch die hohe Wassermenge zudem DEUTLICH erkennbar. Mit den Power Shots l\u00e4sst sich nicht nur richtig gut zielen, sondern bei einem Treffer wird der Gegner auch richtig nass.<\/p>\n<h2><strong>(Flow) Simulation f\u00fcr epische Wasserschlachten<\/strong><\/h2>\n<p>Aktuell arbeiten 13 Wasserpistolen-Enthusiasten an der weiteren Entwicklung \u2013 mit Hilfe von SOLIDWORKS Tools u.a. zur Simulation von Kunststoffteilen, Spritzgussformen und Fl\u00fcssigkeitsstr\u00f6mungen.<\/p>\n<p>Durch deren Einsatz k\u00f6nnen die Konstrukteure das Produkt simulieren, kleinste \u00c4nderungen virtuell testen und so Unregelm\u00e4\u00dfigkeiten fr\u00fchzeitig beheben. Somit kann die Spyra GmbH nicht nur Ressourcen im Sinne von Zeit und Kosten sparen, sondern garantiert gleichzeitig die bestm\u00f6gliche Funktionsweise der Wasserpistole.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-18371 size-medium\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Spyra_Andreas_Schober_01-200x300.jpg\" alt=\"Spyra Water Guns: Schon l\u00e4ngst keine Geheimwaffe mehr dank SOLIDWORKS Simulation\" width=\"200\" height=\"300\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Spyra_Andreas_Schober_01-200x300.jpg 200w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Spyra_Andreas_Schober_01-410x615.jpg 410w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Spyra_Andreas_Schober_01-768x1152.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Spyra_Andreas_Schober_01-1024x1536.jpg 1024w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Spyra_Andreas_Schober_01-1366x2048.jpg 1366w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Spyra_Andreas_Schober_01-728x1092.jpg 728w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Spyra_Andreas_Schober_01-scaled.jpg 1707w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<blockquote><p>\u201eAufgrund schnell durchf\u00fchrbarer Analysen konnten wir innerhalb k\u00fcrzester Zeit eine aufschlussreiche Aussage \u00fcber den weiteren Entwicklungsweg treffen. Ohne SOLIDWORKS h\u00e4tten wir viele physische Prototypen ben\u00f6tigt und somit weitaus l\u00e4nger gebraucht, um unsere Wasserpistole auf den Markt zu bringen.\u201c<\/p><\/blockquote>\n<p>\u2013 Andreas Schober, Head of Technology<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\nDank der Nutzung von SOLIDWORKS Plastics konnten sie sich schnell Expertise in der Konstruktion mit Plastik aneignen, detaillierte Simulationen und Analysen der Entw\u00fcrfe durchf\u00fchren und notwendige \u00c4nderungen fr\u00fchzeitig identifizieren. Denn schon minimale Unstimmigkeiten \u2013 z.B. bei Form oder Beschaffenheit des Materials \u2013 k\u00f6nnen das Endergebnis ver\u00e4ndern.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18373 size-large\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/211125_FlowAnalyse_SPTO_AS_2-615x370.jpg\" alt=\"Spyra Water Guns: Schon l\u00e4ngst keine Geheimwaffe mehr dank SOLIDWORKS Simulation\" width=\"615\" height=\"370\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/211125_FlowAnalyse_SPTO_AS_2-615x370.jpg 615w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/211125_FlowAnalyse_SPTO_AS_2-300x181.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/211125_FlowAnalyse_SPTO_AS_2-768x462.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/211125_FlowAnalyse_SPTO_AS_2-728x438.jpg 728w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/211125_FlowAnalyse_SPTO_AS_2.jpg 1028w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/><\/p>\n<p>Damit die Hightech-Wasserpistole wie gew\u00fcnscht ein einzelnes, pr\u00e4zises Wassergeschoss abfeuert, muss der Wasserstrahl kompakt sein. Es d\u00fcrfen keine Turbulenzen, Kurven\u00e4nderungen oder Verwirbelungen des Wassers vorkommen. Hier kommt SOLIDWORKS Flow Simulation ins Spiel: Wasserstr\u00f6me lassen sich virtuell darstellen und das Team kann Optimierungen direkt am virtuellen Modell vornehmen.<\/p>\n<p>Die positive Erfahrung mit SOLIDWORKS und das Feedback der Community flie\u00dfen bereits in die Planung von Folgeprojekten ein, die allen Water Battle-Fans auch in Zukunft ein ideales Wasserschlachterlebnis bieten.<\/p>\n<p>Dann muss jetzt nur noch der Sommer kommen.<\/p>\n<p>Unterst\u00fctzt wurden die Wasserpistolen-Spezialisten von Spyra Water Guns durch unseren Fachh\u00e4ndler <a href=\"https:\/\/www.solidpro.de\/\" target=\"_blank\" rel=\"noopener\"><strong>Solidpro GmbH<\/strong><\/a>.<\/p>\n<blockquote><p><span style=\"color: #da291c;\"><strong>Lesen Sie den ganzen Anwenderbericht <a href=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/SW_Casestudy_Spyra_withV_2022.pdf\" target=\"_blank\" rel=\"noopener\">HIER<\/a>\u00a0<\/strong><\/span><\/p><\/blockquote>\n<hr \/>\n<p>Alles Bildmaterial \u00a9 Spyra GmbH, 2021<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was macht eine gute Wasserpistole aus? Der Wasserstrahl nat\u00fcrlich! SOLIDWORKS Simulation konnte dabei helfen, das Wasserschlachterlebnis zu revolutionieren..<\/p>\n... <a href=\"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2022\/01\/spyra-water-guns-schon-laengst-keine-geheimwaffe-mehr-dank-solidworks-simulation.html\">Continued<\/a>","protected":false},"author":373,"featured_media":18369,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"Spyra Water Guns","_yoast_wpseo_metadesc":"Was macht eine gute Wasserpistole aus? Der Wasserstrahl nat\u00fcrlich! SOLIDWORKS Simulation konnte dabei helfen, das Wasserschlachterlebnis zu revolutionieren.","footnotes":""},"categories":[505,397,254,199,2],"tags":[5,335,7,2221,13,3403,3409,3412,3410,3411],"class_list":["post-18366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kundenerfolg-kundenreferenz-case-study","category-news","category-solidworks-flow-simulation","category-solidworks-plastics-2","category-solidworks-simulation","tag-flow-simulation","tag-simulation","tag-solidworks","tag-solidworks-case-study","tag-solidworks-plastics","tag-solidworks-referenzbericht","tag-spyra","tag-spyra-water-guns","tag-wasserpistolen","tag-wasserstrahl"],"acf":[],"_links":{"self":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/18366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/users\/373"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/comments?post=18366"}],"version-history":[{"count":20,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/18366\/revisions"}],"predecessor-version":[{"id":18468,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/18366\/revisions\/18468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/media\/18369"}],"wp:attachment":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/media?parent=18366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/categories?post=18366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/tags?post=18366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}