{"id":12312,"date":"2020-03-13T10:00:58","date_gmt":"2020-03-13T09:00:58","guid":{"rendered":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/?p=12312"},"modified":"2020-03-16T09:56:56","modified_gmt":"2020-03-16T08:56:56","slug":"was-ist-neu-in-solidworks-composer-2020","status":"publish","type":"post","link":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2020\/03\/was-ist-neu-in-solidworks-composer-2020.html","title":{"rendered":"Was ist neu in SOLIDWORKS Composer 2020?"},"content":{"rendered":"<p>Jedes Jahr erwarten uns Verbesserungen der SOLIDWORKS Software-Anwendungen. Auch der SOLIDWORKS Composer bietet mit der Version 2020 neue Funktionen. Wir haben f\u00fcr Sie die besten Neuerungen kurz und knapp zusammengefasst.<\/p>\n<h2 style=\"font-size: 20px; text-align: left;\">Verbesserter Im- und Export im SOLIDWORKS Composer<\/h2>\n<p>Im SOLIDWORKS Composer 2020 stehen Ihnen erweiterte M\u00f6glichkeiten zur Verf\u00fcgung, wenn Sie Daten aus SOLIDWORKS importieren. Zum einen k\u00f6nnen auf Wunsch gespeicherte Ansichten und Explosionsansichten importiert werden, zum anderen k\u00f6nnen Sie nun festlegen, ob Sie Ihre SOLIDWORKS Erscheinungsbilder mit in den Composer \u00fcbernehmen m\u00f6chten.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12313\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-1.jpg\" alt=\"\" width=\"703\" height=\"754\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-1.jpg 703w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-1-280x300.jpg 280w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-1-573x615.jpg 573w\" sizes=\"auto, (max-width: 703px) 100vw, 703px\" \/><\/p>\n<p>Die aus SOLIDWORKS importierten Ansichten stehen Ihnen im Composer als Kameraansichten zur Verf\u00fcgung, sodass Sie hier schnellen Zugriff darauf haben, ohne diese neu anlegen zu m\u00fcssen. Wenn eine Explosionsansicht importiert wurde, wird automatisch eine Kameraansicht pro Explosionsstufe erstellt. So k\u00f6nnen Sie Ihre Demontageanleitungen noch schneller aus vorhandenen Konstruktionsdaten erzeugen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12314\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-2.jpg\" alt=\"\" width=\"1214\" height=\"657\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-2.jpg 1214w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-2-300x162.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-2-615x333.jpg 615w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-2-768x416.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-2-728x394.jpg 728w\" sizes=\"auto, (max-width: 1214px) 100vw, 1214px\" \/><\/p>\n<p>Beim Export gibt es zudem eine Neuerung bez\u00fcglich der Dateiformate f\u00fcr die Ausgabe von Animationen. Hier haben Sie, neben dem bisherigen AVI-Format, zus\u00e4tzlich die M\u00f6glichkeit Ihre Videos in den Formaten FLV, MKV, sowie MP4 zu speichern.<\/p>\n<h2 style=\"font-size: 20px; text-align: left;\">Anmerkungen und Pfeile<\/h2>\n<p>Ab der Version 2020 ist es im SOLIDWORKS Composer m\u00f6glich, Pfeile direkt mit eingebetteten Texten zu versehen. Sie k\u00f6nnen die L\u00e4nge eines Pfeils anzeigen lassen, um anzudeuten wie weit ein Bauteil verschoben werden muss, oder eine benutzerdefinierte Zeichenfolge eingeben. Der Text wird in der von Ihnen ausgew\u00e4hlten Farbe direkt im Pfeil erzeugt. Dadurch k\u00f6nnen Sie beispielsweise Ihrer Demontageanleitung weitere n\u00fctzliche Hinweise hinzuf\u00fcgen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12315\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-3.jpg\" alt=\"\" width=\"1214\" height=\"657\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-3.jpg 1214w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-3-300x162.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-3-615x333.jpg 615w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-3-768x416.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-3-728x394.jpg 728w\" sizes=\"auto, (max-width: 1214px) 100vw, 1214px\" \/><\/p>\n<h2 style=\"font-size: 20px; text-align: left;\">St\u00fcckliste und Callouts<\/h2>\n<p>Die bereits in Vorg\u00e4ngerversionen vorhandene Funktion \u201eSt\u00fccklisten nach sichtbaren Callouts zu filtern\u201c, wurde in SOLIDWORKS Composer 2020 um eine weitere Option erg\u00e4nzt. Es ist zus\u00e4tzlich m\u00f6glich, nur nach Callouts zu filtern die eine BOM-ID beinhalten. Wenn kein Filter gesetzt ist, werden alle Positionen in der St\u00fcckliste angezeigt, egal ob sich ein Callout am Teil befindet oder nicht.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12316\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-4.jpg\" alt=\"\" width=\"1358\" height=\"736\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-4.jpg 1358w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-4-300x163.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-4-615x333.jpg 615w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-4-768x416.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-4-728x395.jpg 728w\" sizes=\"auto, (max-width: 1358px) 100vw, 1358px\" \/><\/p>\n<p>Wird der Filter \u201eSichtbare Callouts\u201c gesetzt, welcher bereits in vorherigen Versionen vorhanden war, werden nur Positionen angezeigt bei denen sich ein Callout am Teil befindet.<\/p>\n<p>Wird nun ein Callout am Teil angebracht, welches nur aus einem Text besteht, w\u00fcrde die Position mit dem zuvor genannten Filter in der St\u00fcckliste erscheinen. Mit dem neuen Filter \u201eBOM-ID Callouts\u201c erscheint die Position nicht in der St\u00fcckliste, da keine Positionsnummer im Callout vorkommt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12317\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-5.jpg\" alt=\"\" width=\"1354\" height=\"733\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-5.jpg 1354w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-5-300x162.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-5-615x333.jpg 615w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-5-768x416.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-5-728x394.jpg 728w\" sizes=\"auto, (max-width: 1354px) 100vw, 1354px\" \/><\/p>\n<p>Bei Mengenexponenten an Callouts gibt es in SOLIDWORKS Composer 2020 zus\u00e4tzlich die M\u00f6glichkeit diese zu hinterlegen bzw. hervorzuheben. Die Hervorhebung erfolgt hierbei in der F\u00fcllfarbe des Callouts.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12318\" src=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-6.jpg\" alt=\"\" width=\"1214\" height=\"863\" srcset=\"https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-6.jpg 1214w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-6-300x213.jpg 300w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-6-615x437.jpg 615w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-6-768x546.jpg 768w, https:\/\/blog-assets.solidworks.com\/uploads\/sites\/7\/Was-ist-neu-in-SOLIDWORKS-Composer-www.coffee.de-6-728x518.jpg 728w\" sizes=\"auto, (max-width: 1214px) 100vw, 1214px\" \/><\/p>\n<p><b><span data-contrast=\"none\">Sie m\u00f6chten\u00a0<\/span><\/b><b><span data-contrast=\"none\">mehr Infos zum Thema SOLIDWORKS Composer und technische Kommunikation erhalten?\u00a0<\/span><\/b><b><span data-contrast=\"none\">Dann z\u00f6gern Sie nicht und nehmen Sie noch heute Kontakt mit den Spezialisten unseres\u00a0<\/span><\/b><a href=\"https:\/\/www.coffee.de\/angebote\/solidworks-simulation-aktion?utm_source=solidworks-blog&amp;utm_medium=blogpost&amp;utm_campaign=SW-Inspection\"><b><span data-contrast=\"none\">SOLIDWORKS Partner COFFEE<\/span><\/b><\/a><b><span data-contrast=\"none\">\u202f<\/span><\/b><b><span data-contrast=\"none\">auf. Hier geht\u2019s zum<\/span><\/b><a href=\"https:\/\/www.coffee.de\/live-chat?utm_source=solidworks-blog&amp;utm_medium=blogpost&amp;utm_campaign=SW-Inspection\"><b><span data-contrast=\"none\">\u00a0Chat<\/span><\/b><\/a><b><span data-contrast=\"none\">\u202f!<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559738&quot;:40,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Autor:\u00a0<\/span><span data-contrast=\"none\">COFFEE GmbH<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559738&quot;:120,&quot;335559739&quot;:120,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jedes Jahr erwarten uns Verbesserungen der SOLIDWORKS Software-Anwendungen. Auch der SOLIDWORKS Composer bietet mit der Version 2020 neue Funktionen. Wir haben f\u00fcr Sie die besten Neuerungen kurz und knapp zusammengefasst.<\/p>\n... <a href=\"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/2020\/03\/was-ist-neu-in-solidworks-composer-2020.html\">Continued<\/a>","protected":false},"author":384,"featured_media":12322,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"SOLIDWORKS Composer 2020","_yoast_wpseo_metadesc":"Jedes Jahr erwarten uns Verbesserungen in der SOLIDWORKS Software. Auch der SOLIDWORKS Composer 2020 bietet wieder neue, anwenderbasierte Funktionen.","footnotes":""},"categories":[954,397,170,93],"tags":[1856,277,126,69,1544],"class_list":["post-12312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neue-funktionen","category-news","category-solidworks-composer-3dvia","category-tipps-und-tricks","tag-sw2020","tag-composer","tag-technische-dokumentation","tag-technische-kommunikation","tag-whats-new"],"acf":[],"_links":{"self":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/12312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/users\/384"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/comments?post=12312"}],"version-history":[{"count":5,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/12312\/revisions"}],"predecessor-version":[{"id":12364,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/posts\/12312\/revisions\/12364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/media\/12322"}],"wp:attachment":[{"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/media?parent=12312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/categories?post=12312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.solidworks.com\/solidworksdeutschland\/wp-json\/wp\/v2\/tags?post=12312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}